{"id":4637,"date":"2019-12-27T10:17:13","date_gmt":"2019-12-27T10:17:13","guid":{"rendered":"https:\/\/tornabuoniart.com\/?p=4637"},"modified":"2020-04-03T17:28:54","modified_gmt":"2020-04-03T16:28:54","slug":"mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art","status":"publish","type":"videos","link":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/","title":{"rendered":"Mimmo Rotella | 2012 | Parigi"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/tornabuoniart.com\/it\/video\/\"><span style=\"color: #808080;\"><em>&lt;&lt; torna ai video<\/em><\/span><\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/83512373&#8243; align=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; torna ai video [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/83512373&#8243; align=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"featured_media":4228,"parent":0,"menu_order":109,"template":"","class_list":["post-4637","videos","type-videos","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mimmo Rotella | 2012 | Parigi - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mimmo Rotella | 2012 | Parigi - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; torna ai video [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/83512373&#8243; align=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-03T16:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/10\/Video-Button-rotella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"378\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/\",\"name\":\"Mimmo Rotella | 2012 | Parigi - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Video-Button-rotella.jpg\",\"datePublished\":\"2019-12-27T10:17:13+00:00\",\"dateModified\":\"2020-04-03T16:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Video-Button-rotella.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Video-Button-rotella.jpg\",\"width\":378,\"height\":212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/videos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mimmo Rotella | 2012 | Parigi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mimmo Rotella | 2012 | Parigi - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/","og_locale":"it_IT","og_type":"article","og_title":"Mimmo Rotella | 2012 | Parigi - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; torna ai video [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/83512373&#8243; align=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_modified_time":"2020-04-03T16:28:54+00:00","og_image":[{"width":378,"height":212,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/10\/Video-Button-rotella.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TornabuoniArt","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/","url":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/","name":"Mimmo Rotella | 2012 | Parigi - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/10\/Video-Button-rotella.jpg","datePublished":"2019-12-27T10:17:13+00:00","dateModified":"2020-04-03T16:28:54+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/10\/Video-Button-rotella.jpg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/10\/Video-Button-rotella.jpg","width":378,"height":212},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/videos\/mimmo-rotella-30-mars-14-juin-2012-tornabuoni-art\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/it\/"},{"@type":"ListItem","position":2,"name":"Video","item":"https:\/\/www.tornabuoniart.com\/it\/videos\/"},{"@type":"ListItem","position":3,"name":"Mimmo Rotella | 2012 | Parigi"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]}]}},"ptb_metabox":[],"ptb_taxonomy":[],"ptb_featured_image":{"url":"https:\/\/tornabuoniart.com\/wp-content\/uploads\/2019\/10\/Video-Button-rotella.jpg","title":"Video-Button-rotella","caption":""},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/videos\/4637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/videos"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/types\/videos"}],"version-history":[{"count":1,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/videos\/4637\/revisions"}],"predecessor-version":[{"id":19053,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/videos\/4637\/revisions\/19053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media\/4228"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media?parent=4637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}