{"id":62631,"date":"2025-05-28T17:28:09","date_gmt":"2025-05-28T16:28:09","guid":{"rendered":"https:\/\/www.tornabuoniart.com\/?p=62631"},"modified":"2025-09-25T09:49:04","modified_gmt":"2025-09-25T08:49:04","slug":"claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025","status":"publish","type":"post","link":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/","title":{"rendered":"&#8220;Claudio Parmiggiani&#8221; | Estorick Collection, Londra | maggio &#8211; agosto 2025"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><a style=\"color: #808080;\" href=\"https:\/\/tornabuoniart.com\/it\/news-it\/\">&lt;&lt; torna alle news<\/a><\/em><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;62613&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Claudio Parmiggiani<\/strong><br \/>\n28 maggio &#8211; 31 agosto, 2025<br \/>\nEstorick Collection of Modern Italian Art, Londra<\/p>\n<p style=\"text-align: left;\">Tornabuoni Art ha il piacere di collaborare con la Estorick Collection e l\u2019Archivio dell\u2019artista alla prima mostra istituzionale nel Regno Unito dedicata a Claudio Parmiggiani con il supporto del Consolato Generale d\u2019Italia a Londra.<\/p>\n<p>Attraverso una selezione di opere realizzate negli ultimi cinquant&#8217;anni della sua carriera, l\u2019esposizione mette in evidenza la distintiva esplorazione dell\u2019artista sui temi della memoria, dell\u2019assenza e del silenzio nella sua \u201cricerca di un\u2019immagine, un oggetto o un assemblaggio che trascenda il tempo e l\u2019esperienza individuale per evocare una verit\u00e0 universale ed esistenziale\u201d.<\/p>\n<p>La mostra presenta sia opere monumentali che lavori pi\u00f9 intimi della serie delle <em>Delocazioni<\/em>, opere che utilizzano fumo e fuliggine per creare impressioni spettrali dello spazio negativo lasciato da oggetti vari. Ricordando dei fotogrammi ma con una fragilit\u00e0 e un potere evocativo ancora maggiori, questi lavori contemplativi si configurano come meditazioni poetiche sulla memoria. Questi ultimi sono integrati da lavori su carta e assemblaggi tridimensionali che l\u2019artista definisce \u201cpitture scolpite\u201d.<\/p>\n<p>La mostra \u00e8 accompagnata da un catalogo illustrato e sar\u00e0 visibile alla Estorick Collection di Londra fino al 31 agosto 2025.<\/p>\n<p><a href=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/Press-Release-Claudio-Parmiggiani.pdf\">Maggiori informazioni<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; torna alle news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;62613&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] Claudio Parmiggiani 28 maggio &#8211; 31 agosto, 2025 Estorick Collection of Modern Italian Art,<\/p>\n","protected":false},"author":5,"featured_media":62613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[318,1],"tags":[],"class_list":["post-62631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-318","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Claudio Parmiggiani&quot; | Estorick Collection, Londra | maggio - agosto 2025 - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Claudio Parmiggiani&quot; | Estorick Collection, Londra | maggio - agosto 2025 - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; torna alle news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;62613&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] Claudio Parmiggiani 28 maggio &#8211; 31 agosto, 2025 Estorick Collection of Modern Italian Art,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T16:28:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T08:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/IMG_0017_1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TornabuoniArte Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"TornabuoniArte Paris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/\"},\"author\":{\"name\":\"TornabuoniArte Paris\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\"},\"headline\":\"&#8220;Claudio Parmiggiani&#8221; | Estorick Collection, Londra | maggio &#8211; agosto 2025\",\"datePublished\":\"2025-05-28T16:28:09+00:00\",\"dateModified\":\"2025-09-25T08:49:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0017_1-scaled.jpeg\",\"articleSection\":[\"2025\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/\",\"name\":\"\\\"Claudio Parmiggiani\\\" | Estorick Collection, Londra | maggio - agosto 2025 - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0017_1-scaled.jpeg\",\"datePublished\":\"2025-05-28T16:28:09+00:00\",\"dateModified\":\"2025-09-25T08:49:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0017_1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_0017_1-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Veduta della mostra, Claudio Parmiggiani, Estorick Collection Londra, maggio-agosto 2025, Courtesy Tornabuoni Art\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Claudio Parmiggiani&#8221; | Estorick Collection, Londra | maggio &#8211; agosto 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\",\"name\":\"TornabuoniArte Paris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"caption\":\"TornabuoniArte Paris\"},\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/author\\\/tornabuoniartparis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Claudio Parmiggiani\" | Estorick Collection, Londra | maggio - agosto 2025 - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/","og_locale":"it_IT","og_type":"article","og_title":"\"Claudio Parmiggiani\" | Estorick Collection, Londra | maggio - agosto 2025 - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; torna alle news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;62613&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] Claudio Parmiggiani 28 maggio &#8211; 31 agosto, 2025 Estorick Collection of Modern Italian Art,","og_url":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_published_time":"2025-05-28T16:28:09+00:00","article_modified_time":"2025-09-25T08:49:04+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/IMG_0017_1-scaled.jpeg","type":"image\/jpeg"}],"author":"TornabuoniArte Paris","twitter_card":"summary_large_image","twitter_creator":"@TornabuoniArt","twitter_site":"@TornabuoniArt","twitter_misc":{"Scritto da":"TornabuoniArte Paris","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/"},"author":{"name":"TornabuoniArte Paris","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0"},"headline":"&#8220;Claudio Parmiggiani&#8221; | Estorick Collection, Londra | maggio &#8211; agosto 2025","datePublished":"2025-05-28T16:28:09+00:00","dateModified":"2025-09-25T08:49:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/IMG_0017_1-scaled.jpeg","articleSection":["2025","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/","url":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/","name":"\"Claudio Parmiggiani\" | Estorick Collection, Londra | maggio - agosto 2025 - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/IMG_0017_1-scaled.jpeg","datePublished":"2025-05-28T16:28:09+00:00","dateModified":"2025-09-25T08:49:04+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/IMG_0017_1-scaled.jpeg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/05\/IMG_0017_1-scaled.jpeg","width":2560,"height":1707,"caption":"Veduta della mostra, Claudio Parmiggiani, Estorick Collection Londra, maggio-agosto 2025, Courtesy Tornabuoni Art"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/claudio-parmiggiani-estorick-collection-londra-maggio-agosto-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Claudio Parmiggiani&#8221; | Estorick Collection, Londra | maggio &#8211; agosto 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0","name":"TornabuoniArte Paris","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","caption":"TornabuoniArte Paris"},"url":"https:\/\/www.tornabuoniart.com\/it\/author\/tornabuoniartparis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/62631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/comments?post=62631"}],"version-history":[{"count":5,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/62631\/revisions"}],"predecessor-version":[{"id":63326,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/62631\/revisions\/63326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media\/62613"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media?parent=62631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/categories?post=62631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/tags?post=62631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}