{"id":61337,"date":"2025-01-07T14:08:04","date_gmt":"2025-01-07T13:08:04","guid":{"rendered":"https:\/\/www.tornabuoniart.com\/?p=61337"},"modified":"2025-01-07T17:13:42","modified_gmt":"2025-01-07T16:13:42","slug":"enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate","status":"publish","type":"post","link":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/","title":{"rendered":"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#8217;arte nucleare\u201d \u2013 MUST, Vimercate"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><a style=\"color: #808080;\" href=\"https:\/\/tornabuoniart.com\/it\/news-it\/\">&lt;&lt; torna alle news<\/a><\/em><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;60675&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Bum! Enrico Baj e l&#8217;arte Nucleare<\/strong><br \/>\nMUST, Vimercate<br \/>\n26 gennaio \u2013 05 maggio 2024<\/p>\n<p>Tornabuoni Art ha il piacere di partecipare alla mostra &#8220;BUM! Enrico Baj e l\u2019arte nucleare&#8221;, aperta dal 27 gennaio al 5 maggio 2024 presso il MUST, il museo di Vimercate, tramite il prestito di due opere di Enrico Baj, &#8220;Figure&#8221; del 1956 e &#8220;Personnage&#8221; del 1962-1963, e di una tela di Gianni Dova, &#8220;R\u00eave Scenografia per balletto&#8221; del 1957.<\/p>\n<p>Curata da Simona Bartolena, con una selezione di 25 opere provenienti da collezioni private e gallerie, la mostra offre l\u2019occasione di esplorare la figura di Enrico Baj, il suo stile inconfondibile e l\u2019impatto comunicativo delle sue creazioni e di quelle degli artisti che, negli anni Cinquanta, condivisero con lui l\u2019obiettivo di rinnovare profondamente la pittura, partendo dall\u2019Informale per trasformarlo e superarlo.<\/p>\n<p>La mostra narra cos\u00ec lo sviluppo del Movimento Nucleare attraverso una selezione di opere firmate dagli artisti che maggiormente hanno contribuito alla nascita del movimento, il cui nome traeva spunto dal tema particolarmente attuale della fissione atomica.<\/p>\n<p>Nel percorso espositivo, il visitatore \u00e8 guidato alla scoperta dell\u2019audacia straordinaria dell\u2019arte nucleare e delle successive evoluzioni del lavoro di Enrico Baj, che di questa stagione fu tra i grandi protagonisti.<\/p>\n<p>La mostra sar\u00e0 aperta al pubblico fino al 5 maggio 2024.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; torna alle news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;60675&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Bum! Enrico Baj e l&#8217;arte Nucleare MUST, Vimercate 26 gennaio \u2013 05 maggio 2024 Tornabuoni<\/p>\n","protected":false},"author":5,"featured_media":60675,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[309,1],"tags":[],"class_list":["post-61337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-309","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#039;arte nucleare\u201d \u2013 MUST, Vimercate - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#039;arte nucleare\u201d \u2013 MUST, Vimercate - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; torna alle news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;60675&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Bum! Enrico Baj e l&#8217;arte Nucleare MUST, Vimercate 26 gennaio \u2013 05 maggio 2024 Tornabuoni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-07T13:08:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-07T16:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/11\/baj-personnage-1962-1963.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1593\" \/>\n\t<meta property=\"og:image:height\" content=\"1251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TornabuoniArte Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"TornabuoniArte Paris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/\"},\"author\":{\"name\":\"TornabuoniArte Paris\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\"},\"headline\":\"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#8217;arte nucleare\u201d \u2013 MUST, Vimercate\",\"datePublished\":\"2025-01-07T13:08:04+00:00\",\"dateModified\":\"2025-01-07T16:13:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/\"},\"wordCount\":279,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baj-personnage-1962-1963.jpg\",\"articleSection\":[\"2024\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/\",\"name\":\"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l'arte nucleare\u201d \u2013 MUST, Vimercate - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baj-personnage-1962-1963.jpg\",\"datePublished\":\"2025-01-07T13:08:04+00:00\",\"dateModified\":\"2025-01-07T16:13:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baj-personnage-1962-1963.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baj-personnage-1962-1963.jpg\",\"width\":1593,\"height\":1251},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#8217;arte nucleare\u201d \u2013 MUST, Vimercate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\",\"name\":\"TornabuoniArte Paris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"caption\":\"TornabuoniArte Paris\"},\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/author\\\/tornabuoniartparis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l'arte nucleare\u201d \u2013 MUST, Vimercate - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/","og_locale":"it_IT","og_type":"article","og_title":"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l'arte nucleare\u201d \u2013 MUST, Vimercate - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; torna alle news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;60675&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Bum! Enrico Baj e l&#8217;arte Nucleare MUST, Vimercate 26 gennaio \u2013 05 maggio 2024 Tornabuoni","og_url":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_published_time":"2025-01-07T13:08:04+00:00","article_modified_time":"2025-01-07T16:13:42+00:00","og_image":[{"width":1593,"height":1251,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/11\/baj-personnage-1962-1963.jpg","type":"image\/jpeg"}],"author":"TornabuoniArte Paris","twitter_card":"summary_large_image","twitter_creator":"@TornabuoniArt","twitter_site":"@TornabuoniArt","twitter_misc":{"Scritto da":"TornabuoniArte Paris","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/"},"author":{"name":"TornabuoniArte Paris","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0"},"headline":"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#8217;arte nucleare\u201d \u2013 MUST, Vimercate","datePublished":"2025-01-07T13:08:04+00:00","dateModified":"2025-01-07T16:13:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/"},"wordCount":279,"publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/11\/baj-personnage-1962-1963.jpg","articleSection":["2024","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/","url":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/","name":"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l'arte nucleare\u201d \u2013 MUST, Vimercate - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/11\/baj-personnage-1962-1963.jpg","datePublished":"2025-01-07T13:08:04+00:00","dateModified":"2025-01-07T16:13:42+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/11\/baj-personnage-1962-1963.jpg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/11\/baj-personnage-1962-1963.jpg","width":1593,"height":1251},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/enrico-baj-e-gianni-dova-alla-mostra-bum-enrico-baj-e-larte-nucleare-must-vimercate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/it\/"},{"@type":"ListItem","position":2,"name":"Enrico Baj e Gianni Dova alla mostra \u201cBum! Enrico Baj e l&#8217;arte nucleare\u201d \u2013 MUST, Vimercate"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0","name":"TornabuoniArte Paris","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","caption":"TornabuoniArte Paris"},"url":"https:\/\/www.tornabuoniart.com\/it\/author\/tornabuoniartparis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/61337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/comments?post=61337"}],"version-history":[{"count":4,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/61337\/revisions"}],"predecessor-version":[{"id":61375,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/61337\/revisions\/61375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media\/60675"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media?parent=61337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/categories?post=61337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/tags?post=61337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}