{"id":45757,"date":"2022-04-12T15:02:13","date_gmt":"2022-04-12T14:02:13","guid":{"rendered":"https:\/\/www.tornabuoniart.com\/?p=45757"},"modified":"2022-05-06T15:47:29","modified_gmt":"2022-05-06T14:47:29","slug":"pier-paolo-calzolari-on-fire","status":"publish","type":"post","link":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/","title":{"rendered":"Pier Paolo Calzolari &#8211; On Fire"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><a style=\"color: #808080;\" href=\"https:\/\/tornabuoniart.com\/it\/on-fire\/\">&lt;&lt; torna al menu<\/a><\/em><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/698619044&#8243;][vc_separator][vc_empty_space][vc_separator][vc_column_text]<\/p>\n<h2 style=\"text-align: left;\">Vedute della mostre<\/h2>\n<p>[\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;47117,47108,47111,47114&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Opere in mostra<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45765&#8243; img_size=&#8221;1260&#215;843&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45771&#8243; img_size=&#8221;1132&#215;688&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;24px&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45768&#8243; img_size=&#8221;1226&#215;1552&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45774&#8243; img_size=&#8221;1343&#215;765&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_separator][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div class=\"page\" title=\"Page 44\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 39\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 49\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 58\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 53\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h2>Per me il fuoco e\u0300 una delle energie primarie che guardo in maniera elementare, democratica e orizzontale.<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;24px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space][vc_column_text]<\/p>\n<div class=\"page\" title=\"Page 44\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 39\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"page\" title=\"Page 49\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 58\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 53\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h4 style=\"text-align: center;\">Pier Paolo Calzolari, Lisbona, 2022<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_separator][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Cos\u00ec come concettualizzato nell\u2019Arte Povera, <strong>Pier Paolo<\/strong> <strong>Calzolari<\/strong> lavora fin dall\u2019inizio con materiali in costante conversazione tra loro, umili e provenienti dai contesti semi-industriali urbani o elementi naturali. Tra questi ci sono il fuoco, il legno, ma anche rottami, oggetti quotidiani e tubi al neon. Le sue opere sono opere d\u2019incontro in tutti i sensi, tra lo spettatore e l\u2019oggetto che vive nel quotidiano, ma che in questo caso ha subito una trasformazione, ma anche tra elementi artificiali e lavorati in opposizione all\u2019elemento naturale e allo stato primordiale, come il fuoco. Dal 21 al 24 aprile, in occasione della vernice, si terr\u00e0 la performance <em>Mangiafuoco<\/em> in cui un vero e proprio performer sputer\u00e0 fuoco a cadenza oraria, dalle 11 alle 19.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_separator][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;47120&#8243; img_size=&#8221;large&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"page\" title=\"Page 69\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 67\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 71\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 75\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 73\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Nato a Bologna nel 1943, <strong>Pier Paolo Calzolari<\/strong> trascorre l\u2019infanzia e l\u2019adolescenza a Venezia, il cui patrimonio artistico ed estetico lascia una traccia profonda sulla sensibilita\u0300 del futuro artista.<\/p>\n<p>Nel 1965 realizza a Bologna i primi lavori di pittura e presenta i primi film di Ari Marcopoulos, Andy Warhol, Jonas Mekas e Mario Schifano. Nel frattempo, incontra personaggi come Allen Ginsberg, Julian Beck, Luigi Ontani, Raymond Hains e Chet Baker. Nel 1966-1967 realizza la prima delle sue opere-performance, che coinvolge gli spettatori in una partecipazione diretta dell\u2019opera e che Calzolari stesso definisce una \u201cattivazione dello spazio\u201d. Tra il 1967 e il 1972 si muove tra Parigi, New York e Berlino e porta a maturazione il suo progetto artistico.<\/p>\n<p>E\u0300 in questi anni che Calzolari viene incluso nel movimento dell\u2019Arte Povera e realizza un ampio ciclo di lavori con strutture ghiaccianti e neon in cui la formazione della brina sulle forme, sancita dal passaggio del tempo, e\u0300 indice del processo di trasformazione alchemica della materia. In questo modo gli oggetti e i materiali che l\u2019artista utilizza fin dal 1967 (fuoco, ghiaccio, piombo, stagno, sale, muschio, tabacco), conoscono una seconda vita accanto agli elementi luminosi, traccia della lucentezza del marmo veneziano.<\/p>\n<p>A partire dal 1972, l\u2019artista si concentra sullo studio di una pittura anticonvenzionale. Preferendo nuovi \u201csupporti\u201d, come la flanella o fogli di cartone incollati sulla tela, l\u2019artista giustappone segni pittorici a oggetti reali, come piccole barche di carta o trenini in movimento lungo percorsi ripetuti all\u2019infinito, portando il rituale della quotidianita\u0300 sul piano dell\u2019esperienza estetica e in rapporto orizzontale con il mondo e con la storia, pur continuando a cercare di mantenere un legame con il coinvolgimento fisico delle persone.<\/p>\n<p>Il suo percorso, malgrado la prossimita\u0300 evidente con la produzione coeva degli artisti suoi contemporanei, e\u0300 caratterizzato da diversi elementi peculiari: la volonta\u0300 di saturazione dei sensi, la modalita\u0300 nel rendere visibili i dati del pensiero astratto e l\u2019essenza delle cose, nonche\u0301 l\u2019attenzione particolare rivolta alla fragilita\u0300 di oggetti e materiali.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; torna al menu [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/698619044&#8243;][vc_separator][vc_empty_space][vc_separator][vc_column_text] Vedute della mostre [\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;47117,47108,47111,47114&#8243; img_size=&#8221;full&#8221;][vc_column_text] Opere in mostra [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45765&#8243; img_size=&#8221;1260&#215;843&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_single_image<\/p>\n","protected":false},"author":5,"featured_media":45318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[295,1],"tags":[],"class_list":["post-45757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-295","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pier Paolo Calzolari - On Fire - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pier Paolo Calzolari - On Fire - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; torna al menu [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/698619044&#8243;][vc_separator][vc_empty_space][vc_separator][vc_column_text] Vedute della mostre [\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;47117,47108,47111,47114&#8243; img_size=&#8221;full&#8221;][vc_column_text] Opere in mostra [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45765&#8243; img_size=&#8221;1260&#215;843&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_single_image\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-12T14:02:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-06T14:47:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2022\/03\/vignettes4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2041\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TornabuoniArte Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"TornabuoniArte Paris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/\"},\"author\":{\"name\":\"TornabuoniArte Paris\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\"},\"headline\":\"Pier Paolo Calzolari &#8211; On Fire\",\"datePublished\":\"2022-04-12T14:02:13+00:00\",\"dateModified\":\"2022-05-06T14:47:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/\"},\"wordCount\":785,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/vignettes4-scaled.jpg\",\"articleSection\":[\"2022\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/\",\"name\":\"Pier Paolo Calzolari - On Fire - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/vignettes4-scaled.jpg\",\"datePublished\":\"2022-04-12T14:02:13+00:00\",\"dateModified\":\"2022-05-06T14:47:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/vignettes4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/vignettes4-scaled.jpg\",\"width\":2041,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/pier-paolo-calzolari-on-fire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pier Paolo Calzolari &#8211; On Fire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\",\"name\":\"TornabuoniArte Paris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"caption\":\"TornabuoniArte Paris\"},\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/author\\\/tornabuoniartparis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pier Paolo Calzolari - On Fire - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/","og_locale":"it_IT","og_type":"article","og_title":"Pier Paolo Calzolari - On Fire - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; torna al menu [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/vimeo.com\/698619044&#8243;][vc_separator][vc_empty_space][vc_separator][vc_column_text] Vedute della mostre [\/vc_column_text][vc_gallery interval=&#8221;3&#8243; images=&#8221;47117,47108,47111,47114&#8243; img_size=&#8221;full&#8221;][vc_column_text] Opere in mostra [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_empty_space height=&#8221;24px&#8221;][vc_single_image image=&#8221;45765&#8243; img_size=&#8221;1260&#215;843&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_empty_space height=&#8221;24px&#8221;][vc_single_image","og_url":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_published_time":"2022-04-12T14:02:13+00:00","article_modified_time":"2022-05-06T14:47:29+00:00","og_image":[{"width":2041,"height":2560,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2022\/03\/vignettes4-scaled.jpg","type":"image\/jpeg"}],"author":"TornabuoniArte Paris","twitter_card":"summary_large_image","twitter_creator":"@TornabuoniArt","twitter_site":"@TornabuoniArt","twitter_misc":{"Scritto da":"TornabuoniArte Paris","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/"},"author":{"name":"TornabuoniArte Paris","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0"},"headline":"Pier Paolo Calzolari &#8211; On Fire","datePublished":"2022-04-12T14:02:13+00:00","dateModified":"2022-05-06T14:47:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/"},"wordCount":785,"publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2022\/03\/vignettes4-scaled.jpg","articleSection":["2022","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/","url":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/","name":"Pier Paolo Calzolari - On Fire - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2022\/03\/vignettes4-scaled.jpg","datePublished":"2022-04-12T14:02:13+00:00","dateModified":"2022-05-06T14:47:29+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2022\/03\/vignettes4-scaled.jpg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2022\/03\/vignettes4-scaled.jpg","width":2041,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/pier-paolo-calzolari-on-fire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/it\/"},{"@type":"ListItem","position":2,"name":"Pier Paolo Calzolari &#8211; On Fire"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0","name":"TornabuoniArte Paris","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","caption":"TornabuoniArte Paris"},"url":"https:\/\/www.tornabuoniart.com\/it\/author\/tornabuoniartparis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/45757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/comments?post=45757"}],"version-history":[{"count":3,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/45757\/revisions"}],"predecessor-version":[{"id":47123,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/posts\/45757\/revisions\/47123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media\/45318"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media?parent=45757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/categories?post=45757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/tags?post=45757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}