{"id":2770,"date":"2019-09-13T14:32:55","date_gmt":"2019-09-13T14:32:55","guid":{"rendered":"https:\/\/tornabuoniart.com\/?post_type=portfolio&#038;p=2770"},"modified":"2026-07-06T10:34:24","modified_gmt":"2026-07-06T09:34:24","slug":"scanavino-emilio","status":"publish","type":"portfolio","link":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/","title":{"rendered":"Scanavino Emilio"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/tornabuoniart.com\/it\/artisti\/\"><span style=\"color: #808080;\"><em>&lt;&lt; torna agli artisti<\/em><\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_single_image image=&#8221;7930&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1579273839671{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;]<div class=\"mpc-carousel__wrapper mpc-waypoint\"><div id=\"mpc_carousel_image-846a580dfe2236b\" class=\"mpc-carousel-image mpc-init mpc-layout--fluid mpc-effect--none mpc-force-height  mpc-overlay--fade\"  data-mpcslick='{\"infinite\":true,\"autoplay\":false,\"slidesToShow\":3,\"slidesToScroll\":1,\"centerMode\":false,\"initialSlide\":0,\"rows\":1,\"variableWidth\":true,\"speed\":500}' data-slick-cols=\"3\" data-align=\"middle-center\"><div target=\"\"class=\"mpc-carousel__item-wrapper\" data-height=\"1024\"><div onclick=\"\" class=\"mpc-item mpc-transition\"><div class=\"mpc-border\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1671\" height=\"2074\" src=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" title=\"Scanavino, Il cerchio, 1970 92x73 cm\" srcset=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm.jpg 1671w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-242x300.jpg 242w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-825x1024.jpg 825w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-768x953.jpg 768w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-1238x1536.jpg 1238w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-1650x2048.jpg 1650w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-60x75.jpg 60w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-580x720.jpg 580w, https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm-480x596.jpg 480w\" sizes=\"auto, (max-width:767px) 480px, (max-width:1671px) 100vw, 1671px\" \/><div class=\"mpc-item-overlay mpc-transition\"><div class=\"mpc-overlay--vertical-wrap\"><div class=\"mpc-overlay--vertical\"><a href=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2024\/12\/Scanavino-Il-cerchio-1970-92x73-cm.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"Scanavino, Il cerchio, 1970 92&#215;73 cm\" data-rl_caption=\"Scanavino, Il cerchio, 1970 92&#215;73 cm\" data-magnific_type=\"gallery\" class=\"mpc-icon-anchor mpc-magnific-popup\" title=\"Scanavino, Il cerchio, 1970 92&#215;73 cm\"><i class=\"mpc-item-overlay__icon mpc-type--lightbox fa fa-arrows mpc-icon--icon\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--left mpc-navigation--style_3 mpc-on-hover  mpc-nav-preset--preset_3\" data-mpcslider=\"mpc_carousel_image-846a580dfe2236b\"><div class=\"mpc-nav__arrow mpcslick-prev\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_carrot-left\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/i><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--left mpc-navigation--style_3 mpc-on-hover  mpc-nav-preset--preset_3\" data-mpcslider=\"mpc_carousel_image-846a580dfe2236b\"><div class=\"mpc-nav__arrow mpcslick-next\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_carrot-right\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/i><\/div><\/div><\/div><\/div>[vc_column_text css=&#8221;.vc_custom_1578667400636{margin-top: 25px !important;padding-top: 0px !important;}&#8221; el_id=&#8221;biography&#8221;]<\/p>\n<h2>biografia<\/h2>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;testo-giustificato&#8221;]Genova, 1922 \u2013 Milano, 1986<\/p>\n<p>Emilio Scanavino \u00e8 stato un pittore e uno scultore italiano.<\/p>\n<p>Nel 1942 si iscrive alla Facolt\u00e0 di Architettura dell\u2019Universit\u00e0 di Milano, ma contemporaneamente presenta la sua prima mostra personale presso il Salone Romano di Genova. Lo scoppio della guerra lo costringe ad abbandonare gli studi e andare al fronte.<\/p>\n<p>Una volta tornato in patria, inizia a lavorare come disegnatore tecnico presso l\u2019amministrazione comunale di Genova e aderisce al clima di rinnovamento culturale e artistico della sua citt\u00e0. Nel frattempo continua la sua attivit\u00e0 artistica, producendo una serie di tele dove ricorrono moduli linguistici di declinazioni espressionista.<\/p>\n<p>Nel 1947 Scanavino si reca per la prima volta a Parigi dove soggiorna qualche tempo e, accanto ai critici, incontra i poeti e gli artisti, Edouard Jaguer, Wols, Camille Bryen.<\/p>\n<p>L\u2019esperienza parigina si riveler\u00e0 fondamentale nel suo percorso stilistico, in particolare per l\u2019influenza che il postcubismo, reinterpretato in chiave personale, avr\u00e0 sulla sua produzione successiva.<\/p>\n<p>Nel 1950 espone alla XXV Biennale di Venezia (dove torner\u00e0 diverse volte), ricevendo l\u2019attenzione della critica. L\u2019anno successivo ottiene una mostra personale alla Apollinaire Gallery di Londra, dove conosce Philip Martin, Eduardo Paolozzi e Francis Bacon.<\/p>\n<p>Tornato in Italia, si trasferisce per un periodo ad Albisola per frequentare il laboratorio di ceramica di Tullio d\u2019Albisola. Qui incontra e stringe amicizia con Fontana, Dangelo, Baj, Dova, Crippa, Jorn, Appel, Corneille del gruppo Cobra, Matta, Lam.<\/p>\n<p>Gli anni 50 sono segnati da un suo avvicinamento al gruppo milanese degli Spaziali, al quale non aderir\u00e0 mai formalmente. In questi anni, inoltre, Scanavino viaggia spesso tra Londra e Parigi. Nascono in questo periodo i primi Rituali e gli Alfabeti senza fine, i temi che ricorrono nella pittura di Scanavino, dove il segno si fa protagonista sulla tela di pieni e vuoti di presenze suggestive.<\/p>\n<p>La Biennale di Venezia lo invita ancora nel 1958, e nel 1960 e nel 1966 con una sala personale.<\/p>\n<p>Nel 1971 si trasferisce per qualche tempo a Roma ed \u00e8 invitato alla Biennale di San Paolo del Brasile insieme con Alik Cavaliere: i due artisti realizzano l\u2019opera-installazione Omaggio all\u2019America Latina, dedicata ai Martiri per la libert\u00e0 dei popoli latinoamericani.<\/p>\n<p>Lungo gli anni Settanta Scanavino il suo segno si semplifica e si raccoglie in griglie o architetture geometriche, che preludono a una riflessione sull\u2019oggettivazione della pittura.<\/p>\n<p>Nel 1973 la Kunsthalle di Darmstadt gli dedica una vasta e approfondita antologicache sar\u00e0 esposta anche a Venezia a Palazzo Grassi e a Milano a Palazzo Reale.[\/vc_column_text][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1568023296154{padding-top: 50px !important;padding-bottom: 10px !important;}&#8221; el_id=&#8221;exhibition&#8221;]<\/p>\n<h2>mostre<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#8221;ids&#8221; element_width=&#8221;12&#8243; item=&#8221;4321&#8243; grid_id=&#8221;vc_gid:1783330453283-c001e1a2-de39-9&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1578667642547{padding-top: 50px !important;padding-bottom: 10px !important;}&#8221; el_id=&#8221;fairs&#8221;]<\/p>\n<h2>fiere<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#8221;ids&#8221; element_width=&#8221;6&#8243; item=&#8221;4545&#8243; grid_id=&#8221;vc_gid:1783330453284-2a78ad32-af58-10&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1575889020947{padding-top: 50px !important;padding-bottom: 10px !important;}&#8221; el_id=&#8221;video&#8221;]<\/p>\n<h2>video<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#8221;ids&#8221; element_width=&#8221;6&#8243; item=&#8221;1469&#8243; grid_id=&#8221;vc_gid:1783330453285-5275bcd9-413b-0&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; el_class=&#8221;blocco-pubblicazioni&#8221;][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1568023309353{padding-top: 50px !important;padding-bottom: 10px !important;}&#8221; el_id=&#8221;publication&#8221;]<\/p>\n<h2>pubblicazioni<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#8221;ids&#8221; element_width=&#8221;12&#8243; item=&#8221;4344&#8243; grid_id=&#8221;vc_gid:1783330453285-f7f9d7f8-a21e-9&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;100px&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text] &lt;&lt; torna agli artisti [\/vc_column_text][vc_single_image image=&#8221;7930&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1579273839671{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221;<\/p>\n","protected":false},"author":2,"featured_media":-1,"menu_order":236,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"portfolio-types":[51],"class_list":["post-2770","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-s"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scanavino Emilio - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scanavino Emilio - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text] &lt;&lt; torna agli artisti [\/vc_column_text][vc_single_image image=&#8221;7930&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1579273839671{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T09:34:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/scanavino-emilio\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/scanavino-emilio\\\/\",\"name\":\"Scanavino Emilio - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"datePublished\":\"2019-09-13T14:32:55+00:00\",\"dateModified\":\"2026-07-06T09:34:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/scanavino-emilio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/scanavino-emilio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/scanavino-emilio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scanavino Emilio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scanavino Emilio - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/","og_locale":"it_IT","og_type":"article","og_title":"Scanavino Emilio - Tornabuoni Art","og_description":"[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text] &lt;&lt; torna agli artisti [\/vc_column_text][vc_single_image image=&#8221;7930&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1579273839671{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221;","og_url":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_modified_time":"2026-07-06T09:34:24+00:00","twitter_card":"summary_large_image","twitter_site":"@TornabuoniArt","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/","url":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/","name":"Scanavino Emilio - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"datePublished":"2019-09-13T14:32:55+00:00","dateModified":"2026-07-06T09:34:24+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/artisti\/scanavino-emilio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/it\/"},{"@type":"ListItem","position":2,"name":"Scanavino Emilio"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/portfolio\/2770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/comments?post=2770"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media?parent=2770"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/portfolio-types?post=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}