{"id":2622,"date":"2019-09-13T09:06:28","date_gmt":"2019-09-13T09:06:28","guid":{"rendered":"https:\/\/tornabuoniart.com\/?post_type=portfolio&#038;p=2622"},"modified":"2026-01-09T17:19:06","modified_gmt":"2026-01-09T16:19:06","slug":"morandi-giorgio","status":"publish","type":"portfolio","link":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/","title":{"rendered":"Morandi Giorgio"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/tornabuoniart.com\/it\/artisti\/\"><span style=\"color: #808080;\"><em>&lt;&lt; torna agli artisti<\/em><\/span><\/a><\/p>\n<p>[\/vc_column_text][vc_single_image image=&#8221;58150&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1714732332842{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1578667400636{margin-top: 25px !important;padding-top: 0px !important;}&#8221; el_id=&#8221;biography&#8221;]<\/p>\n<h2>biografia<\/h2>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221; el_class=&#8221;testo-giustificato&#8221;]Bologna, 1890 &#8211; Bologna, 1964<\/p>\n<p>Morandi Giorgio \u00e8 un pittore e incisore italiano. Il suo quasi proverbiale isolamento dal clima culturale italiano del tempo e il severo controllo dei mezzi espressivi connaturato alla sua pittura ne hanno favorito per lungo tempo un\u2019interpretazione \u201ccrepuscolare\u201d.<\/p>\n<p>La critica pi\u00f9 recente ha messo in luce la piena appartenenza di Morandi a una cultura che non \u00e8 quella della cronaca immediata, ma si trova nella storia. Morandi non ha aderito che sporadicamente ai movimenti italiani della prima met\u00e0 del novecento; il suo periodo metafisico (1918-20) fu pi\u00f9 conseguente alla logica interna della sua opera che non agli intenti di quella corrente. Ma quest\u2019indifferenza non \u00e8 che la contropartita dell\u2019attenzione che Morandi dedic\u00f2 a maestri come C\u00e9zanne, Vermeer, Chardin, Corot e al fascino che sent\u00ec per Giotto e i maestri del primo Quattrocento, la cui lezione si avverte soprattutto nelle nature morte del periodo metafisico.<\/p>\n<p>La sua produzione segue una personale regola estetica che nasce dalla coerenza dei rapporti tra l\u2019ordine meditatissimo delle forme e le variazioni impercettibili del colore in una gamma di bianchi, gialli, ocra, grigi, rosa, violacei sia nelle sue celebri nature morte che nei suoi paesaggi. Usare pochissimi colori \u00e8 una sua particolare caratteristica, che lo rende poetico e surreale e anche se non particolareggi i suoi soggetti in modo ossessivo, si pu\u00f2 notare come questi non perdano di realismo.<\/p>\n<p>Immediatamente dopo il 1930 l\u2019artista giunse a sfaldare le forme consuete della sua figurazione (bottiglie, caraffe, fruttiere, vasi di fiori, vecchie lucerne) in una materia di colore spesso e sobrio, di tanto in tanto ravvivato da gamme squillanti.<\/p>\n<p>Accanto all\u2019opera pittorica affiancata a pregevoli disegni e acquerelli Morandi coltiv\u00f2 costantemente l\u2019arte dell\u2019incisione di cui \u00e8 maestro indiscusso, talvolta trasportando l\u2019acquaforte nel dipinto, talvolta percorrendo un processo inverso sempre con i suoi consueti temi che lo contraddistinguono e rendono unico nel panorama della storia dell\u2019arte. Le opere, realizzate con grande cura, sono caratterizzate da segni sottili e rettilinei in un intreccio molto complesso di tratti con cui raggiunge dimensioni prospettiche di grande efficacia.<\/p>\n<p>\u00a9 GIORGIO MORANDI, by SIAE 2026[\/vc_column_text][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1578667642547{padding-top: 50px !important;padding-bottom: 10px !important;}&#8221; el_id=&#8221;fairs&#8221;]<\/p>\n<h2>fiere<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#8221;ids&#8221; element_width=&#8221;6&#8243; item=&#8221;4545&#8243; grid_id=&#8221;vc_gid:1767975520489-c11e1e14-9c4d-2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;100px&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text] &lt;&lt; torna agli artisti [\/vc_column_text][vc_single_image image=&#8221;58150&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1714732332842{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221;<\/p>\n","protected":false},"author":2,"featured_media":-1,"menu_order":260,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"portfolio-types":[45],"class_list":["post-2622","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-m"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morandi Giorgio - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morandi Giorgio - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text] &lt;&lt; torna agli artisti [\/vc_column_text][vc_single_image image=&#8221;58150&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1714732332842{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T16:19:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/morandi-giorgio\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/morandi-giorgio\\\/\",\"name\":\"Morandi Giorgio - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"datePublished\":\"2019-09-13T09:06:28+00:00\",\"dateModified\":\"2026-01-09T16:19:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/morandi-giorgio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/morandi-giorgio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/artisti\\\/morandi-giorgio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morandi Giorgio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morandi Giorgio - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/","og_locale":"it_IT","og_type":"article","og_title":"Morandi Giorgio - Tornabuoni Art","og_description":"[vc_row css=&#8221;.vc_custom_1577099752877{margin-top: 100px !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;100&#8243; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1547225524376{margin-bottom: 50px !important;}&#8221;][vc_column_text] &lt;&lt; torna agli artisti [\/vc_column_text][vc_single_image image=&#8221;58150&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1714732332842{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h1|font_size:22%20px|text_align:center|line_height:30%20px&#8221;","og_url":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_modified_time":"2026-01-09T16:19:06+00:00","twitter_card":"summary_large_image","twitter_site":"@TornabuoniArt","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/","url":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/","name":"Morandi Giorgio - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"datePublished":"2019-09-13T09:06:28+00:00","dateModified":"2026-01-09T16:19:06+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/artisti\/morandi-giorgio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/it\/"},{"@type":"ListItem","position":2,"name":"Morandi Giorgio"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/portfolio\/2622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/comments?post=2622"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/media?parent=2622"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/it\/wp-json\/wp\/v2\/portfolio-types?post=2622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}