{"id":44326,"date":"2021-12-17T09:47:49","date_gmt":"2021-12-17T08:47:49","guid":{"rendered":"https:\/\/www.tornabuoniart.com\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/"},"modified":"2021-12-17T09:54:57","modified_gmt":"2021-12-17T08:54:57","slug":"alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba","status":"publish","type":"post","link":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/","title":{"rendered":"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><a style=\"color: #808080;\" href=\"https:\/\/www.tornabuoniart.com\/fr\/news-fr\/\">&lt;&lt; retourner aux news<\/a><\/em><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Fondazione Ferrero &#8211; Alba <\/strong><\/p>\n<p style=\"text-align: center;\">9 octobre 2021 &#8211; 30 janvier 2022<\/p>\n<p>Tornabuoni Art a le plaisir d&#8217;annoncer le pr\u00eat de l&#8217;\u0153uvre d&#8217;Alberto Burri &#8216;Combustione B.A.&#8217; (1960) pour l&#8217;exposition \u00ab<strong>Burri. La poesia della materia<\/strong>\u00bb \u00e0 la Fondazione Ferrero \u00e0 Alba.<\/p>\n<p>L&#8217;exposition, organis\u00e9e par Bruno Cor\u00e0, pr\u00e9sident de la Fondazione Palazzo Albizzini Collezione Burri, met en valeur l&#8217;ensemble de la production de l&#8217;artiste \u00e0 travers une r\u00e9trospective de plus de quarante \u0153uvres r\u00e9alis\u00e9es pendant toute sa carri\u00e8re.<\/p>\n<p>L&#8217;exposition durera jusqu&#8217;au 30 janvier 2022.<\/p>\n<p><a href=\"https:\/\/www.fondazioneferrero.it\/mostra-burri\">En savoir plus sur l&#8217;exposition<\/a><\/p>\n<p>\u00a9\u00a0Image: Vue d\u2019exposition, \u2018Burri. La poesia della materia&#8217;, Fondazione Ferrero, Alba.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; retourner aux news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Fondazione Ferrero &#8211; Alba 9 octobre 2021 &#8211; 30 janvier 2022 Tornabuoni Art a le plaisir<\/p>\n","protected":false},"author":3,"featured_media":44321,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[290,264],"tags":[],"class_list":["post-44326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2021-fr","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; retourner aux news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Fondazione Ferrero &#8211; Alba 9 octobre 2021 &#8211; 30 janvier 2022 Tornabuoni Art a le plaisir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-17T08:47:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-17T08:54:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/12\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Firenze\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Firenze\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/\"},\"author\":{\"name\":\"Firenze\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/df67e3de137dec2798fe14b939eb7b55\"},\"headline\":\"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba\",\"datePublished\":\"2021-12-17T08:47:49+00:00\",\"dateModified\":\"2021-12-17T08:54:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg\",\"articleSection\":[\"2021\",\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/\",\"name\":\"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg\",\"datePublished\":\"2021-12-17T08:47:49+00:00\",\"dateModified\":\"2021-12-17T08:54:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg\",\"width\":2560,\"height\":1480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/df67e3de137dec2798fe14b939eb7b55\",\"name\":\"Firenze\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g\",\"caption\":\"Firenze\"},\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/fr\\\/author\\\/tornabuoniartfirenze\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/","og_locale":"fr_FR","og_type":"article","og_title":"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; retourner aux news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Fondazione Ferrero &#8211; Alba 9 octobre 2021 &#8211; 30 janvier 2022 Tornabuoni Art a le plaisir","og_url":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_published_time":"2021-12-17T08:47:49+00:00","article_modified_time":"2021-12-17T08:54:57+00:00","og_image":[{"width":2560,"height":1480,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/12\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg","type":"image\/jpeg"}],"author":"Firenze","twitter_card":"summary_large_image","twitter_creator":"@TornabuoniArt","twitter_site":"@TornabuoniArt","twitter_misc":{"Written by":"Firenze","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/"},"author":{"name":"Firenze","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/df67e3de137dec2798fe14b939eb7b55"},"headline":"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba","datePublished":"2021-12-17T08:47:49+00:00","dateModified":"2021-12-17T08:54:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/"},"wordCount":173,"publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/12\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg","articleSection":["2021","News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/","url":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/","name":"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/12\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg","datePublished":"2021-12-17T08:47:49+00:00","dateModified":"2021-12-17T08:54:57+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/12\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/12\/9556bb94-c674-fdcf-7a11-fc88e3d004ed-scaled.jpg","width":2560,"height":1480},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/fr\/alberto-burri-a-lexposition-burri-la-poesia-della-materia-fondazione-ferrero-alba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Alberto Burri \u00e0 l\u2019exposition \u00ab Burri. La poesia della materia \u00bb \u2013 Fondazione Ferrero, Alba"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/df67e3de137dec2798fe14b939eb7b55","name":"Firenze","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g","caption":"Firenze"},"url":"https:\/\/www.tornabuoniart.com\/fr\/author\/tornabuoniartfirenze\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/posts\/44326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/comments?post=44326"}],"version-history":[{"count":2,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/posts\/44326\/revisions"}],"predecessor-version":[{"id":44328,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/posts\/44326\/revisions\/44328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/media\/44321"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/media?parent=44326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/categories?post=44326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/fr\/wp-json\/wp\/v2\/tags?post=44326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}