{"id":63352,"date":"2025-09-24T17:20:02","date_gmt":"2025-09-24T16:20:02","guid":{"rendered":"https:\/\/www.tornabuoniart.com\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/"},"modified":"2025-09-25T10:14:37","modified_gmt":"2025-09-25T09:14:37","slug":"colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello","status":"publish","type":"post","link":"https:\/\/www.tornabuoniart.com\/en\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/","title":{"rendered":"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &#8220;METALLICA. Scultura in Italia 1947-2025&#8221; | Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><a style=\"color: #808080;\" href=\"https:\/\/tornabuoniart.com\/it\/news-it\/\">&lt;&lt; back to news<\/a><\/em><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery interval=&#8221;3&#8243; images=&#8221;63346,63349,63343&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>METALLICA. Scultura in Italia 1947-2025<\/strong><br \/>\nPalazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello<br \/>\nMarch 30 &#8211; June 29 2025<\/p>\n<p>Tornabuoni Art is pleased to announce the loan of six works for the exhibition <em>METALLICA. Scultura in Italia 1947\u20132025<\/em>, held at Palazzo Vitelli a Sant\u2019Egidio in Citt\u00e0 di Castello.<\/p>\n<p>The gallery contributes the following works: <em>Marte<\/em> (1965) by Ettore Colla, <em>Ettore e Andromaca<\/em> (2001) by Giorgio de Chirico, <em>Seme d\u2019arancia<\/em> (2007\u20132015) by Emilio Isgr\u00f2, <em>Studio per grandi pieghe<\/em> (1978) by Giacomo Manz\u00f9, <em>Guerriero<\/em> (1958\u201359) by Marino Marini, and <em>Figura con stella<\/em> (2000\u20132002) by Mimmo Paladino.<\/p>\n<p>Curated by Bruno Cor\u00e0, the exhibition explores the use of metal in Italian sculpture from the 1940s to the present, highlighting how this material has been interpreted by successive generations through heterogeneous languages and sensibilities. From Fontana\u2019s spatialist gestures to Isgr\u00f2\u2019s conceptual experimentation, through de Chirico\u2019s reinterpretation of myth and Marini\u2019s plastic forms, metal emerges as both an expressive and symbolic medium capable of transcending eras and artistic visions.<\/p>\n<p>The exhibition is promoted by the Associazione Palazzo Vitelli a Sant\u2019Egidio, in collaboration with the Fondazione Palazzo Albizzini Collezione Burri, on the occasion of the palace\u2019s restoration and reopening to the public, and anticipates the inauguration of the future Center for Contemporary Arts Documentation.<\/p>\n<p>The exhibition is on view until 29 June 2025.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; back to news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery interval=&#8221;3&#8243; images=&#8221;63346,63349,63343&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] METALLICA. Scultura in Italia 1947-2025 Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello March 30 &#8211;<\/p>\n","protected":false},"author":5,"featured_media":63342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[319,263],"tags":[],"class_list":["post-63352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2025-en","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &quot;METALLICA. Scultura in Italia 1947-2025&quot; | Palazzo Vitelli a Sant&#039;Egidio, Citt\u00e0 di Castello - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &quot;METALLICA. Scultura in Italia 1947-2025&quot; | Palazzo Vitelli a Sant&#039;Egidio, Citt\u00e0 di Castello - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; back to news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery interval=&#8221;3&#8243; images=&#8221;63346,63349,63343&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] METALLICA. Scultura in Italia 1947-2025 Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello March 30 &#8211;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T16:20:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T09:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/09\/P__C3148-1024x682.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TornabuoniArte Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"TornabuoniArte Paris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/\"},\"author\":{\"name\":\"TornabuoniArte Paris\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\"},\"headline\":\"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &#8220;METALLICA. Scultura in Italia 1947-2025&#8221; | Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello\",\"datePublished\":\"2025-09-24T16:20:02+00:00\",\"dateModified\":\"2025-09-25T09:14:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/\"},\"wordCount\":286,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/P__C3148.jpg\",\"articleSection\":[\"2025\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/\",\"name\":\"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition \\\"METALLICA. Scultura in Italia 1947-2025\\\" | Palazzo Vitelli a Sant'Egidio, Citt\u00e0 di Castello - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/P__C3148.jpg\",\"datePublished\":\"2025-09-24T16:20:02+00:00\",\"dateModified\":\"2025-09-25T09:14:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/P__C3148.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/P__C3148.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Exhibition view, METALLICA. Scultura in Italia 1947-2025, Palazzo Vitelli a Sant'Egidio, Citt\u00e0 di Castelloi, 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &#8220;METALLICA. Scultura in Italia 1947-2025&#8221; | Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/e3a3961876c55fe7985792c5c806fff0\",\"name\":\"TornabuoniArte Paris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g\",\"caption\":\"TornabuoniArte Paris\"},\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/author\\\/tornabuoniartparis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition \"METALLICA. Scultura in Italia 1947-2025\" | Palazzo Vitelli a Sant'Egidio, Citt\u00e0 di Castello - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/","og_locale":"en_US","og_type":"article","og_title":"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition \"METALLICA. Scultura in Italia 1947-2025\" | Palazzo Vitelli a Sant'Egidio, Citt\u00e0 di Castello - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; back to news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery interval=&#8221;3&#8243; images=&#8221;63346,63349,63343&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] METALLICA. Scultura in Italia 1947-2025 Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello March 30 &#8211;","og_url":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_published_time":"2025-09-24T16:20:02+00:00","article_modified_time":"2025-09-25T09:14:37+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/09\/P__C3148-1024x682.jpg","type":"image\/jpeg"}],"author":"TornabuoniArte Paris","twitter_card":"summary_large_image","twitter_creator":"@TornabuoniArt","twitter_site":"@TornabuoniArt","twitter_misc":{"Written by":"TornabuoniArte Paris","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/"},"author":{"name":"TornabuoniArte Paris","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0"},"headline":"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &#8220;METALLICA. Scultura in Italia 1947-2025&#8221; | Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello","datePublished":"2025-09-24T16:20:02+00:00","dateModified":"2025-09-25T09:14:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/"},"wordCount":286,"publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/09\/P__C3148.jpg","articleSection":["2025","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/","url":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/","name":"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition \"METALLICA. Scultura in Italia 1947-2025\" | Palazzo Vitelli a Sant'Egidio, Citt\u00e0 di Castello - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/09\/P__C3148.jpg","datePublished":"2025-09-24T16:20:02+00:00","dateModified":"2025-09-25T09:14:37+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/09\/P__C3148.jpg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2025\/09\/P__C3148.jpg","width":2000,"height":1333,"caption":"Exhibition view, METALLICA. Scultura in Italia 1947-2025, Palazzo Vitelli a Sant'Egidio, Citt\u00e0 di Castelloi, 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/colla-de-chirico-isgro-manzu-marini-e-paladino-alla-mostra-metallica-scultura-in-italia-1947-2025-palazzo-vitelli-a-santegidio-citta-di-castello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/en\/"},{"@type":"ListItem","position":2,"name":"Colla, de Chirico, Isgr\u00f2, Manz\u00f9, Marini and Paladino at the exhibition &#8220;METALLICA. Scultura in Italia 1947-2025&#8221; | Palazzo Vitelli a Sant&#8217;Egidio, Citt\u00e0 di Castello"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/e3a3961876c55fe7985792c5c806fff0","name":"TornabuoniArte Paris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2bc2bba47aee0dad7617f047f148e7f6d09795b36f82a9708d50a1e02175ba49?s=96&d=mm&r=g","caption":"TornabuoniArte Paris"},"url":"https:\/\/www.tornabuoniart.com\/en\/author\/tornabuoniartparis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts\/63352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/comments?post=63352"}],"version-history":[{"count":5,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts\/63352\/revisions"}],"predecessor-version":[{"id":63407,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts\/63352\/revisions\/63407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/media\/63342"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/media?parent=63352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/categories?post=63352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/tags?post=63352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}