{"id":34552,"date":"2021-06-03T16:47:59","date_gmt":"2021-06-03T15:47:59","guid":{"rendered":"http:\/\/www.tornabuoniart.com\/alighiero-boetti-at-painting-is-back-exhibition-gallerie-ditalia-milan\/"},"modified":"2021-06-08T16:07:10","modified_gmt":"2021-06-08T15:07:10","slug":"alighiero-boetti-at-painting-is-back-exhibition-gallerie-ditalia-milan","status":"publish","type":"post","link":"https:\/\/www.tornabuoniart.com\/en\/alighiero-boetti-at-painting-is-back-exhibition-gallerie-ditalia-milan\/","title":{"rendered":"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><a style=\"color: #808080;\" href=\"https:\/\/www.tornabuoniart.com\/en\/news-en\/\">&lt;&lt; back to news<\/a><\/em><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Gallerie d\u2019Italia\u00a0\u2013 Milan<\/strong><\/p>\n<p style=\"text-align: center;\">2 June \u2013 3 October 2021<\/p>\n<p style=\"text-align: justify;\">Tornabuoni Art is delighted to announce the loan of the work \u2018Senza titolo (Piscine)\u2019 (1980) by Alighiero Boetti for the exhibition \u2018Painting is back. Anni Ottanta la pittura in Italia\u2019 held at Gallerie d\u2019Italia in Milan.<\/p>\n<p style=\"text-align: justify;\">Curated by Luca Massimo Barbero, this group show will focus on the leading figures of the 80s Italian painting, highlighting their provocatory and pictorial dynamism from Transavantgarde to the later generation of artists.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.gallerieditalia.com\/it\/milano\/painting-is-back-anni-ottanta-la-pittura-in-italia\/\" target=\"_blank\" rel=\"noopener\">Find out more about the exhibition<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a9 Image:\u00a0 Alighiero Boetti, <em>Senza titolo (Piscine)<\/em>, 1980, mixed media on paper laid on canvas, 160&#215;225 cm<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &lt;&lt; back to news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Gallerie d\u2019Italia\u00a0\u2013 Milan 2 June \u2013 3 October 2021 Tornabuoni Art is delighted to announce the<\/p>\n","protected":false},"author":3,"featured_media":34548,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[288,1],"tags":[],"class_list":["post-34552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-288","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan - Tornabuoni Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan - Tornabuoni Art\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &lt;&lt; back to news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Gallerie d\u2019Italia\u00a0\u2013 Milan 2 June \u2013 3 October 2021 Tornabuoni Art is delighted to announce the\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornabuoni Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornabuoniArt\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-03T15:47:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-08T15:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/06\/Boetti-17-altissima-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Firenze\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:site\" content=\"@TornabuoniArt\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Firenze\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/\"},\"author\":{\"name\":\"Firenze\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/df67e3de137dec2798fe14b939eb7b55\"},\"headline\":\"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan\",\"datePublished\":\"2021-06-03T15:47:59+00:00\",\"dateModified\":\"2021-06-08T15:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Boetti-17-altissima-scaled.jpg\",\"articleSection\":[\"2021\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/\",\"name\":\"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan - Tornabuoni Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Boetti-17-altissima-scaled.jpg\",\"datePublished\":\"2021-06-03T15:47:59+00:00\",\"dateModified\":\"2021-06-08T15:07:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Boetti-17-altissima-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Boetti-17-altissima-scaled.jpg\",\"width\":2560,\"height\":1811,\"caption\":\"Boetti, Senza titolo (Piscine), 1980, 160x225 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/it\\\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"name\":\"Tornabuoni Art\",\"description\":\"Modern &amp; Contemporary Art Gallery\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#organization\",\"name\":\"Tornabuoni Art\",\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"contentUrl\":\"http:\\\/\\\/www.tornabuoniart.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo_tornabuoni-art2-2-grey.png\",\"width\":961,\"height\":136,\"caption\":\"Tornabuoni Art\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TornabuoniArt\\\/\",\"https:\\\/\\\/x.com\\\/TornabuoniArt\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoniart\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/#\\\/schema\\\/person\\\/df67e3de137dec2798fe14b939eb7b55\",\"name\":\"Firenze\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g\",\"caption\":\"Firenze\"},\"url\":\"https:\\\/\\\/www.tornabuoniart.com\\\/en\\\/author\\\/tornabuoniartfirenze\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan - Tornabuoni Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/","og_locale":"en_US","og_type":"article","og_title":"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan - Tornabuoni Art","og_description":"[vc_row][vc_column][vc_column_text] &lt;&lt; back to news [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image source=&#8221;featured_image&#8221; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] Gallerie d\u2019Italia\u00a0\u2013 Milan 2 June \u2013 3 October 2021 Tornabuoni Art is delighted to announce the","og_url":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/","og_site_name":"Tornabuoni Art","article_publisher":"https:\/\/www.facebook.com\/TornabuoniArt\/","article_published_time":"2021-06-03T15:47:59+00:00","article_modified_time":"2021-06-08T15:07:10+00:00","og_image":[{"width":2560,"height":1811,"url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/06\/Boetti-17-altissima-scaled.jpg","type":"image\/jpeg"}],"author":"Firenze","twitter_card":"summary_large_image","twitter_creator":"@TornabuoniArt","twitter_site":"@TornabuoniArt","twitter_misc":{"Written by":"Firenze","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/"},"author":{"name":"Firenze","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/df67e3de137dec2798fe14b939eb7b55"},"headline":"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan","datePublished":"2021-06-03T15:47:59+00:00","dateModified":"2021-06-08T15:07:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/"},"wordCount":162,"publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/06\/Boetti-17-altissima-scaled.jpg","articleSection":["2021","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/","url":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/","name":"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan - Tornabuoni Art","isPartOf":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/06\/Boetti-17-altissima-scaled.jpg","datePublished":"2021-06-03T15:47:59+00:00","dateModified":"2021-06-08T15:07:10+00:00","breadcrumb":{"@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#primaryimage","url":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/06\/Boetti-17-altissima-scaled.jpg","contentUrl":"https:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2021\/06\/Boetti-17-altissima-scaled.jpg","width":2560,"height":1811,"caption":"Boetti, Senza titolo (Piscine), 1980, 160x225 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoniart.com\/it\/alighiero-boetti-alla-mostra-painting-is-back-gallerie-ditalia-milano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoniart.com\/en\/"},{"@type":"ListItem","position":2,"name":"Alighiero Boetti at \u2018Painting is back\u2019 exhibition \u2013 Gallerie d\u2019Italia, Milan"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoniart.com\/en\/#website","url":"https:\/\/www.tornabuoniart.com\/en\/","name":"Tornabuoni Art","description":"Modern &amp; Contemporary Art Gallery","publisher":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoniart.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tornabuoniart.com\/en\/#organization","name":"Tornabuoni Art","url":"https:\/\/www.tornabuoniart.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","contentUrl":"http:\/\/www.tornabuoniart.com\/wp-content\/uploads\/2019\/04\/logo_tornabuoni-art2-2-grey.png","width":961,"height":136,"caption":"Tornabuoni Art"},"image":{"@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TornabuoniArt\/","https:\/\/x.com\/TornabuoniArt","https:\/\/www.instagram.com\/tornabuoniart\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoniart.com\/en\/#\/schema\/person\/df67e3de137dec2798fe14b939eb7b55","name":"Firenze","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57579b05568f2908a1f0d24a99d0c5030db12b726956c9bed9dc2fc5f6369d60?s=96&d=mm&r=g","caption":"Firenze"},"url":"https:\/\/www.tornabuoniart.com\/en\/author\/tornabuoniartfirenze\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts\/34552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/comments?post=34552"}],"version-history":[{"count":5,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts\/34552\/revisions"}],"predecessor-version":[{"id":34685,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/posts\/34552\/revisions\/34685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/media\/34548"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/media?parent=34552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/categories?post=34552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoniart.com\/en\/wp-json\/wp\/v2\/tags?post=34552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}